{"id":2562,"date":"2018-09-19T09:12:02","date_gmt":"2018-09-19T07:12:02","guid":{"rendered":"https:\/\/www.rekubik.de\/magazin\/?p=2562"},"modified":"2024-05-23T13:14:11","modified_gmt":"2024-05-23T11:14:11","slug":"komposter-selber-bauen","status":"publish","type":"post","link":"https:\/\/www.rekubik.de\/magazin\/komposter-selber-bauen\/","title":{"rendered":"Komposter selber bauen"},"content":{"rendered":"<h2>\u00ab Funktioniert auch mit IBC Containern \u00bb<\/h2>\n<p style=\"text-align: justify;\"><strong>Kompost ist so etwas wie ein perfekter und sogar kosteng\u00fcnstiger D\u00fcnger f\u00fcr den Garten. Gr\u00fcngut und Haushaltsabf\u00e4lle lassen sich durch Kompostieren auf die denkbar umweltschonende Weise entsorgen. Daf\u00fcr ben\u00f6tigt man lediglich einen geeigneten Komposter. Wie sich so ein Kompost selber bauen l\u00e4sst, wie hilfreich ein gebrauchter <a href=\"https:\/\/www.rekubik.de\/ibc-container\/\">IBC Container<\/a> dabei sein kann und worauf es f\u00fcr ein rundum gelungenes Kompostergebnis ankommt, erfahren Sie im Rekubik Magazin!<\/strong><\/p>\n<h2>Gr\u00fcnschnitt und andere Gartenabf\u00e4lle<\/h2>\n<p style=\"text-align: justify;\">Wer seinen eigenen Garten kultiviert, hat in der Regel auch reichlich Gartenabf\u00e4lle. Im Sommer ist das vor allem der Gr\u00fcnschnitt des Rasenm\u00e4hers. Im Herbst kommen Bl\u00e4tter, Zweige und abgestorbene Pflanzen hinzu. Nat\u00fcrlich dr\u00e4ngt sich sofort die Frage auf, wie dieses Material entsorgt werden kann. F\u00fcr den regul\u00e4ren Hausm\u00fcll oder die Biotonne ist die Menge meistens zu gro\u00df \u2013 ganz abgesehen davon, dass Gr\u00fcngut auch viel zu schade daf\u00fcr ist. Es l\u00e4sst sich n\u00e4mlich als Kompost prima wiederverwenden.<\/p>\n<p style=\"text-align: justify;\">Die Vorteile liegen auf der Hand: Es entsteht ein vollkommen nat\u00fcrlicher Kreislauf, der nicht die geringsten Einfl\u00fcsse auf die Umwelt hat. Das Problem dabei: Die Abf\u00e4lle m\u00fcssen erst einmal umgewandelt, also kompostiert werden. Dazu braucht man nicht nur etwas Geduld, sondern vor allem auch einen geeigneten Beh\u00e4lter. Zum Gl\u00fcck gibt es alte, ausrangierte IBC Container, die sich ganz wunderbar eignen, daraus einen Komposter selber zu bauen. Das ist sogar einfacher, als Sie zun\u00e4chst vielleicht denken m\u00f6gen.<\/p>\n<figure id=\"attachment_2579\" aria-describedby=\"caption-attachment-2579\" style=\"width: 800px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-2579 size-full\" title=\"Schubkarre mit Gr\u00fcnschnitt\" src=\"https:\/\/www.rekubik.de\/magazin\/wp-content\/uploads\/2018\/10\/Schubkarre-mit-Gruenschnitt.jpg\" alt=\"Schubkarre mit Gruenschnitt\" width=\"800\" height=\"533\" srcset=\"https:\/\/www.rekubik.de\/magazin\/wp-content\/uploads\/2018\/10\/Schubkarre-mit-Gruenschnitt.jpg 800w, https:\/\/www.rekubik.de\/magazin\/wp-content\/uploads\/2018\/10\/Schubkarre-mit-Gruenschnitt-300x200.jpg 300w, https:\/\/www.rekubik.de\/magazin\/wp-content\/uploads\/2018\/10\/Schubkarre-mit-Gruenschnitt-768x512.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><figcaption id=\"caption-attachment-2579\" class=\"wp-caption-text\">\u00a9 artfocus \/ Fotolia.com<\/figcaption><\/figure>\n<h2>Worauf es beim Kompost ankommt<\/h2>\n<p style=\"text-align: justify;\">Kompostgemisch ist nichts anderes als verrottetes organisches Material. Beim Kompostieren wird dieses auf ganz nat\u00fcrliche Art und Weise umgewandelt \u2013 egal, ob es sich dabei um Rasenschnitt, Bl\u00e4tter, kleine \u00c4ste, Stauden oder auch K\u00fcchenabf\u00e4lle handelt.<\/p>\n<p style=\"text-align: justify;\">Bei der Kompostierung findet ein sogenannter N\u00e4hrstoffkreislauf statt. Das organische Material wird in Verbindung mit Sauerstoff und unter Einwirkung von Kleinstlebewesen aus dem Boden abgebaut. Dabei werden wasserl\u00f6sliche Mineralien freigesetzt, die sich sp\u00e4ter als D\u00fcnger verwenden lassen. Sie sind automatisch im Humus, der w\u00e4hrend des Kompostierungsprozesses entsteht, enthalten. In der Folge muss lediglich der Humus in das Erdreich gemischt werden, um den Pflanzen wichtige N\u00e4hrstoffe zuzuf\u00fchren und den Kreislauf zu schlie\u00dfen.<\/p>\n<blockquote>\n<p style=\"text-align: justify;\">Damit der Kompostierungsvorgang allerdings auch wirklich funktioniert, braucht es vor allem zwei Dinge: Sauerstoff und Mikroorganismen aus dem Boden. Und auch ein spezieller Beh\u00e4lter ist notwendig, in den die organischen Abf\u00e4lle gegeben werden.<\/p>\n<\/blockquote>\n<h2>Komposter im Eigenbau: Warum sich ein gebrauchter IBC Container daf\u00fcr eignet<\/h2>\n<p style=\"text-align: justify;\">Auf den ersten Blick ist ein IBC nicht unbedingt der ideale Beh\u00e4lter, um daraus eine Kompostierungsanlage selber bauen zu k\u00f6nnen. Wie wir bereits wissen, spielen Sauerstoff und Bodenorganismen eine zentrale Rolle beim Kompostierungsvorgang. Die Tankblase eines IBCs ist zwar grunds\u00e4tzlich in der Lage, jede Menge an Material zu fassen, sie ist aber auch weitgehend geschlossen. Sauerstoff kann in sie nur in sehr geringem Umfang eindringen, Mikroorganismen so gut wie gar nicht.<\/p>\n<p style=\"text-align: justify;\">Warum also sollte an dennoch einen IBC Container daf\u00fcr verwenden? Nun, zum einen spielt nat\u00fcrlich auch hier die Nachhaltigkeit eine Rolle. Es macht sicherlich keinen Sinn, einen neuen IBC anzuschaffen, um daraus einen Komposter zu bauen. Hat man jedoch bereits einen alten Container im Garten stehen, der sich als Teil der <a href=\"https:\/\/www.rekubik.de\/bewaesserung\/\">Gartenbew\u00e4sserung<\/a> nicht mehr nutzen l\u00e4sst, ist die Umwandlung die ideale L\u00f6sung \u2013 nicht zuletzt auch, weil man sich damit die Entsorgung sparen kann.<\/p>\n<p style=\"text-align: justify;\">Es gibt aber noch einen anderen Grund: Im Tank selbst l\u00e4sst sich perfekt jenes Mikroklima erzeugen, das f\u00fcr eine erfolgreiche Kompostierung unumg\u00e4nglich ist. Dazu bedarf es allerdings ein paar Umbauarbeiten an der Blase. Diese gestalten sich jedoch kinderleicht und ohne viel Aufwand.<\/p>\n<figure id=\"attachment_2592\" aria-describedby=\"caption-attachment-2592\" style=\"width: 800px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-2592 size-full\" title=\"Regenw\u00fcrmer spielen beim Kompostiervorgang eine wichtige Rolle\" src=\"https:\/\/www.rekubik.de\/magazin\/wp-content\/uploads\/2018\/10\/Regenwuermer.jpg\" alt=\"Regenwuermer\" width=\"800\" height=\"533\" srcset=\"https:\/\/www.rekubik.de\/magazin\/wp-content\/uploads\/2018\/10\/Regenwuermer.jpg 800w, https:\/\/www.rekubik.de\/magazin\/wp-content\/uploads\/2018\/10\/Regenwuermer-300x200.jpg 300w, https:\/\/www.rekubik.de\/magazin\/wp-content\/uploads\/2018\/10\/Regenwuermer-768x512.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><figcaption id=\"caption-attachment-2592\" class=\"wp-caption-text\">\u00a9 Eaknarin \/ Fotolia.com<\/figcaption><\/figure>\n<h2>Einen IBC Komposter in Eigenregie herstellen \u2013 so geht&#8217;s<\/h2>\n<p style=\"text-align: justify;\">In einem ersten Schritt wird der Deckel der Tankblase abgeschnitten. Das ist wichtig, um den Komposter sp\u00e4ter problemlos bef\u00fcllen bzw. entleeren zu k\u00f6nnen. Der Deckel wird in einer H\u00f6he von rund zehn Zentimetern abgetrennt. Am besten verwendet man eine Stichs\u00e4ge, die mit einem S\u00e4geblatt versehen ist, das Kunststoff schneidet. Idealerweise zeichnet man daf\u00fcr eine durchgehende gerade Linie rund um den Tank herum. An dieser Linie kann dann gerade geschnitten werden.<\/p>\n<p style=\"text-align: justify;\">Kleiner Tipp: Mit einer langen Wasserwaage gelingt dieses Anzeichnen um einiges leichter. Ist der Deckel abgetrennt, sollte man die Schnittkanten entgraten bzw. abschleifen, um sp\u00e4tere Verletzungen zu vermeiden. Wichtig ist auch, den abgeschnittenen Deckel aufzubewahren. Er kann zum Beispiel im Winter als Abdeckung noch wertvolle Dienste leisten.<\/p>\n<figure id=\"attachment_2576\" aria-describedby=\"caption-attachment-2576\" style=\"width: 800px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-2576 size-full\" title=\"Stichs\u00e4ge und Wasserwaage\" src=\"https:\/\/www.rekubik.de\/magazin\/wp-content\/uploads\/2018\/10\/Stichsaege-und-Wasserwaage.jpg\" alt=\"Stichsaege und Wasserwaage\" width=\"800\" height=\"533\" srcset=\"https:\/\/www.rekubik.de\/magazin\/wp-content\/uploads\/2018\/10\/Stichsaege-und-Wasserwaage.jpg 800w, https:\/\/www.rekubik.de\/magazin\/wp-content\/uploads\/2018\/10\/Stichsaege-und-Wasserwaage-300x200.jpg 300w, https:\/\/www.rekubik.de\/magazin\/wp-content\/uploads\/2018\/10\/Stichsaege-und-Wasserwaage-768x512.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><figcaption id=\"caption-attachment-2576\" class=\"wp-caption-text\">\u00a9 Ralf Geithe \/ Fotolia.com<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">In einem zweiten Schritt geht es nun darum, f\u00fcr ausreichend Luft im Komposter zu sorgen. Au\u00dferdem m\u00fcssen M\u00f6glichkeiten geschaffen werden, dass die Mikroorganismen aus dem Boden ins Innere der Blase gelangen k\u00f6nnen. Beides erreicht man ganz einfach dadurch, indem man unz\u00e4hlige L\u00f6cher in alle noch vorhandenen Seiten des Tanks bohrt. Die L\u00f6cher d\u00fcrften dabei nicht zu klein sein. Einen Durchmesser von mindestens drei Zentimeter sollten sie schon haben. Da das mit herk\u00f6mmlichen Bohrern nicht funktionieren wird, empfehlen sich spezielle Schneidaufs\u00e4tze f\u00fcr die Bohrmaschine. Die L\u00f6cher im Boden sollten sogar noch einmal deutlich gr\u00f6\u00dfer sein. Alternativ k\u00f6nnen \u00fcbrigens Boden und Deckel einfach abgeschnitten werden. Allerdings leidet darunter die Stabilit\u00e4t der Konstruktion deutlich.<\/p>\n<p style=\"text-align: justify;\">Noch einmal: An den L\u00f6chern darf auf gar keinen Fall gespart werden. Alle Schichten im Inneren der Blase m\u00fcssen sp\u00e4ter gut mit Luft versorgt werden k\u00f6nnen.<\/p>\n<figure id=\"attachment_2599\" aria-describedby=\"caption-attachment-2599\" style=\"width: 800px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-2599 size-full\" title=\"Kompostierung\" src=\"https:\/\/www.rekubik.de\/magazin\/wp-content\/uploads\/2018\/10\/Kompostierung.jpg\" alt=\"Kompostierung\" width=\"800\" height=\"600\" srcset=\"https:\/\/www.rekubik.de\/magazin\/wp-content\/uploads\/2018\/10\/Kompostierung.jpg 800w, https:\/\/www.rekubik.de\/magazin\/wp-content\/uploads\/2018\/10\/Kompostierung-300x225.jpg 300w, https:\/\/www.rekubik.de\/magazin\/wp-content\/uploads\/2018\/10\/Kompostierung-768x576.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><figcaption id=\"caption-attachment-2599\" class=\"wp-caption-text\">\u00a9 M. Schuppich \/ Fotolia.com<\/figcaption><\/figure>\n<h2>Selber bauen und selbst platzieren<\/h2>\n<p style=\"text-align: justify;\">Sie sehen: Eine kleine Kompostierungsanlage selber zu bauen, ist eigentlich kein Problem. In der einfachsten Variante geht man wie oben beschrieben vor und platziert die nackte Tankblase dann an einem geeigneten Ort. Das bedeutet konkret, dass die Blase im Halbschatten und in direktem Kontakt mit dem Erdreich stehen sollte. Die Europalette und die Gitterbox, die nun mal auch zu einem IBC Container geh\u00f6ren, werden damit nicht weiter verwendet.<\/p>\n<blockquote>\n<p style=\"text-align: justify;\">Besteht die Palette hingegen aus Kunststoff und nicht aus Holz, kann man \u00fcberlegen, ob man sie nicht doch verwendet und sie bis zu ihrem oberen Rand in der Erde vergr\u00e4bt.<\/p>\n<\/blockquote>\n<p style=\"text-align: justify;\">Die Gitterbox kann dabei nat\u00fcrlich an ihr befestigt bleiben. Auf diese Weise erreicht man eine ungemein stabile Konstruktion, die selber zu bauen auf einem anderen Weg einen sehr gro\u00dfen Aufwand erfordern w\u00fcrde. Man sollte bei dieser Variante allerdings peinlich darauf achten, dass ein direkter Kontakt zwischen dem Erdreich und den \u00d6ffnungen in der Unterseite beim Komposter besteht. Eventuell m\u00fcssen deshalb kleinere St\u00fccke aus der Palette entfernt werden.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-2571 size-full\" title=\"1000l IBC Container UNGESP\u00dcLT (SIRUP) auf PE-Palette \" src=\"https:\/\/www.rekubik.de\/magazin\/wp-content\/uploads\/2018\/10\/zweite-wahl-1000l-ibc-tank-ungespuelt-auf-misch-palette.jpg\" alt=\"1000l IBC Container UNGESP\u00dcLT (SIRUP) auf PE-Palette \" width=\"600\" height=\"590\" srcset=\"https:\/\/www.rekubik.de\/magazin\/wp-content\/uploads\/2018\/10\/zweite-wahl-1000l-ibc-tank-ungespuelt-auf-misch-palette.jpg 600w, https:\/\/www.rekubik.de\/magazin\/wp-content\/uploads\/2018\/10\/zweite-wahl-1000l-ibc-tank-ungespuelt-auf-misch-palette-300x295.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/p>\n<h2>Komposter selber bauen: Auf die richtige Bef\u00fcllung kommt es an<\/h2>\n<p style=\"text-align: justify;\">Wer sich eine Kompostierungsanlage selber bauen m\u00f6chte, steht \u00fcber kurz oder lang auch vor der Frage, wie genau er sie denn bef\u00fcllen soll. Wichtig dabei ist vor allem, dass die Bef\u00fcllung in wechselnden Schichten erfolgt. Schichten aus trockenem Material wie Gras, zerkleinerten \u00c4sten oder Bl\u00e4ttern sollten sich am besten mit Schichten aus K\u00fcchenabf\u00e4llen wie Tee- oder Kaffeeresten, Gem\u00fcse-, Obst- und Eierschalen abwechseln.<\/p>\n<p style=\"text-align: justify;\">Sorgt man derart f\u00fcr Abwechslung, ist auch das Verh\u00e4ltnis von Stickstoff zu Kohlenstoff im Komposter ausgewogen. In der Folge werden dann mehr Kleinstlebewesen und W\u00fcrmer angezogen, die f\u00fcr das Kompostieren unerl\u00e4sslich sind. Darauf achten sollte man allerdings, dass das eingebrachte Material nicht zu feucht ist, da es sonst zu F\u00e4ulnisprozessen kommen k\u00f6nnte.<\/p>\n<figure id=\"attachment_2587\" aria-describedby=\"caption-attachment-2587\" style=\"width: 800px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-2587 size-full\" title=\"Innerhalb eines Kompostierbeh\u00e4lters\" src=\"https:\/\/www.rekubik.de\/magazin\/wp-content\/uploads\/2018\/10\/Innerhalb-eines-Kompostierbehaelters.jpg\" alt=\"Innerhalb eines Kompostierbehaelters\" width=\"800\" height=\"533\" srcset=\"https:\/\/www.rekubik.de\/magazin\/wp-content\/uploads\/2018\/10\/Innerhalb-eines-Kompostierbehaelters.jpg 800w, https:\/\/www.rekubik.de\/magazin\/wp-content\/uploads\/2018\/10\/Innerhalb-eines-Kompostierbehaelters-300x200.jpg 300w, https:\/\/www.rekubik.de\/magazin\/wp-content\/uploads\/2018\/10\/Innerhalb-eines-Kompostierbehaelters-768x512.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><figcaption id=\"caption-attachment-2587\" class=\"wp-caption-text\">\u00a9 curto \/ Fotolia.com<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>\u00ab Funktioniert auch mit IBC Containern \u00bb Kompost ist so etwas wie ein perfekter und sogar kosteng\u00fcnstiger D\u00fcnger f\u00fcr den Garten. Gr\u00fcngut und Haushaltsabf\u00e4lle lassen sich durch Kompostieren auf die denkbar umweltschonende Weise entsorgen. Daf\u00fcr ben\u00f6tigt man lediglich einen geeigneten Komposter. Wie sich so ein Kompost selber bauen l\u00e4sst, wie hilfreich ein gebrauchter IBC Container &hellip;<\/p>\n","protected":false},"author":1,"featured_media":2578,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[28,42,323,22,322,7,321,320,121,37],"class_list":["post-2562","post","type-post","status-publish","format-standard","has-post-thumbnail","","category-ibc-garten","tag-container","tag-eigenbau","tag-gartenabfall","tag-gebraucht","tag-gruenschnitt","tag-ibc","tag-kompost","tag-komposter","tag-restentleert","tag-tanks"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Komposter selber bauen - REKUBIK\u00ae Magazin<\/title>\n<meta name=\"description\" content=\"Das Rekubik Magazin zeigt, wie Sie aus einem IBC-Tank einen Komposter werden lassen! \u2013 Anleitung zum Selberbauen \u2714 Mehr aus IBC \u2714\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rekubik.de\/magazin\/komposter-selber-bauen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Komposter selber bauen - REKUBIK\u00ae Magazin\" \/>\n<meta property=\"og:description\" content=\"Das Rekubik Magazin zeigt, wie Sie aus einem IBC-Tank einen Komposter werden lassen! \u2013 Anleitung zum Selberbauen \u2714 Mehr aus IBC \u2714\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rekubik.de\/magazin\/komposter-selber-bauen\/\" \/>\n<meta property=\"og:site_name\" content=\"REKUBIK\u00ae Magazin\" \/>\n<meta property=\"article:published_time\" content=\"2018-09-19T07:12:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-23T11:14:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rekubik.de\/magazin\/wp-content\/uploads\/2018\/10\/Komposter-selber-bauen.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"667\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschrieben von\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"8\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.rekubik.de\/magazin\/komposter-selber-bauen\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.rekubik.de\/magazin\/komposter-selber-bauen\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\/\/www.rekubik.de\/magazin\/#\/schema\/person\/d5faea021aac94edeeb8e47cf06771c7\"},\"headline\":\"Komposter selber bauen\",\"datePublished\":\"2018-09-19T07:12:02+00:00\",\"dateModified\":\"2024-05-23T11:14:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.rekubik.de\/magazin\/komposter-selber-bauen\/\"},\"wordCount\":1285,\"publisher\":{\"@id\":\"https:\/\/www.rekubik.de\/magazin\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.rekubik.de\/magazin\/komposter-selber-bauen\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.rekubik.de\/magazin\/wp-content\/uploads\/2018\/10\/Komposter-selber-bauen.jpg\",\"keywords\":[\"Container\",\"Eigenbau\",\"Gartenabfall\",\"gebraucht\",\"Gr\u00fcnschnitt\",\"IBC\",\"Kompost\",\"Komposter\",\"restentleert\",\"Tanks\"],\"articleSection\":[\"IBC IM GARTEN\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.rekubik.de\/magazin\/komposter-selber-bauen\/\",\"url\":\"https:\/\/www.rekubik.de\/magazin\/komposter-selber-bauen\/\",\"name\":\"Komposter selber bauen - REKUBIK\u00ae Magazin\",\"isPartOf\":{\"@id\":\"https:\/\/www.rekubik.de\/magazin\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.rekubik.de\/magazin\/komposter-selber-bauen\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.rekubik.de\/magazin\/komposter-selber-bauen\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.rekubik.de\/magazin\/wp-content\/uploads\/2018\/10\/Komposter-selber-bauen.jpg\",\"datePublished\":\"2018-09-19T07:12:02+00:00\",\"dateModified\":\"2024-05-23T11:14:11+00:00\",\"description\":\"Das Rekubik Magazin zeigt, wie Sie aus einem IBC-Tank einen Komposter werden lassen! \u2013 Anleitung zum Selberbauen \u2714 Mehr aus IBC \u2714\",\"breadcrumb\":{\"@id\":\"https:\/\/www.rekubik.de\/magazin\/komposter-selber-bauen\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.rekubik.de\/magazin\/komposter-selber-bauen\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.rekubik.de\/magazin\/komposter-selber-bauen\/#primaryimage\",\"url\":\"https:\/\/www.rekubik.de\/magazin\/wp-content\/uploads\/2018\/10\/Komposter-selber-bauen.jpg\",\"contentUrl\":\"https:\/\/www.rekubik.de\/magazin\/wp-content\/uploads\/2018\/10\/Komposter-selber-bauen.jpg\",\"width\":1000,\"height\":667,\"caption\":\"\u00a9 Marina Lohrbach \/ Fotolia.com\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.rekubik.de\/magazin\/komposter-selber-bauen\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.rekubik.de\/magazin\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Komposter selber bauen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.rekubik.de\/magazin\/#website\",\"url\":\"https:\/\/www.rekubik.de\/magazin\/\",\"name\":\"REKUBIK\u00ae Magazin\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.rekubik.de\/magazin\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.rekubik.de\/magazin\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.rekubik.de\/magazin\/#organization\",\"name\":\"Rekubik\",\"url\":\"https:\/\/www.rekubik.de\/magazin\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.rekubik.de\/magazin\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.rekubik.de\/magazin\/wp-content\/uploads\/2017\/12\/rekubik-LOGO-Shopware.png\",\"contentUrl\":\"https:\/\/www.rekubik.de\/magazin\/wp-content\/uploads\/2017\/12\/rekubik-LOGO-Shopware.png\",\"width\":200,\"height\":50,\"caption\":\"Rekubik\"},\"image\":{\"@id\":\"https:\/\/www.rekubik.de\/magazin\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.rekubik.de\/magazin\/#\/schema\/person\/d5faea021aac94edeeb8e47cf06771c7\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.rekubik.de\/magazin\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a794a4fe8a9b9c52241597eb381dfa2e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a794a4fe8a9b9c52241597eb381dfa2e?s=96&d=mm&r=g\",\"caption\":\"admin\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Komposter selber bauen - REKUBIK\u00ae Magazin","description":"Das Rekubik Magazin zeigt, wie Sie aus einem IBC-Tank einen Komposter werden lassen! \u2013 Anleitung zum Selberbauen \u2714 Mehr aus IBC \u2714","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rekubik.de\/magazin\/komposter-selber-bauen\/","og_locale":"de_DE","og_type":"article","og_title":"Komposter selber bauen - REKUBIK\u00ae Magazin","og_description":"Das Rekubik Magazin zeigt, wie Sie aus einem IBC-Tank einen Komposter werden lassen! \u2013 Anleitung zum Selberbauen \u2714 Mehr aus IBC \u2714","og_url":"https:\/\/www.rekubik.de\/magazin\/komposter-selber-bauen\/","og_site_name":"REKUBIK\u00ae Magazin","article_published_time":"2018-09-19T07:12:02+00:00","article_modified_time":"2024-05-23T11:14:11+00:00","og_image":[{"width":1000,"height":667,"url":"https:\/\/www.rekubik.de\/magazin\/wp-content\/uploads\/2018\/10\/Komposter-selber-bauen.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Geschrieben von":"admin","Gesch\u00e4tzte Lesezeit":"8\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rekubik.de\/magazin\/komposter-selber-bauen\/#article","isPartOf":{"@id":"https:\/\/www.rekubik.de\/magazin\/komposter-selber-bauen\/"},"author":{"name":"admin","@id":"https:\/\/www.rekubik.de\/magazin\/#\/schema\/person\/d5faea021aac94edeeb8e47cf06771c7"},"headline":"Komposter selber bauen","datePublished":"2018-09-19T07:12:02+00:00","dateModified":"2024-05-23T11:14:11+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rekubik.de\/magazin\/komposter-selber-bauen\/"},"wordCount":1285,"publisher":{"@id":"https:\/\/www.rekubik.de\/magazin\/#organization"},"image":{"@id":"https:\/\/www.rekubik.de\/magazin\/komposter-selber-bauen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rekubik.de\/magazin\/wp-content\/uploads\/2018\/10\/Komposter-selber-bauen.jpg","keywords":["Container","Eigenbau","Gartenabfall","gebraucht","Gr\u00fcnschnitt","IBC","Kompost","Komposter","restentleert","Tanks"],"articleSection":["IBC IM GARTEN"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.rekubik.de\/magazin\/komposter-selber-bauen\/","url":"https:\/\/www.rekubik.de\/magazin\/komposter-selber-bauen\/","name":"Komposter selber bauen - REKUBIK\u00ae Magazin","isPartOf":{"@id":"https:\/\/www.rekubik.de\/magazin\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rekubik.de\/magazin\/komposter-selber-bauen\/#primaryimage"},"image":{"@id":"https:\/\/www.rekubik.de\/magazin\/komposter-selber-bauen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rekubik.de\/magazin\/wp-content\/uploads\/2018\/10\/Komposter-selber-bauen.jpg","datePublished":"2018-09-19T07:12:02+00:00","dateModified":"2024-05-23T11:14:11+00:00","description":"Das Rekubik Magazin zeigt, wie Sie aus einem IBC-Tank einen Komposter werden lassen! \u2013 Anleitung zum Selberbauen \u2714 Mehr aus IBC \u2714","breadcrumb":{"@id":"https:\/\/www.rekubik.de\/magazin\/komposter-selber-bauen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rekubik.de\/magazin\/komposter-selber-bauen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.rekubik.de\/magazin\/komposter-selber-bauen\/#primaryimage","url":"https:\/\/www.rekubik.de\/magazin\/wp-content\/uploads\/2018\/10\/Komposter-selber-bauen.jpg","contentUrl":"https:\/\/www.rekubik.de\/magazin\/wp-content\/uploads\/2018\/10\/Komposter-selber-bauen.jpg","width":1000,"height":667,"caption":"\u00a9 Marina Lohrbach \/ Fotolia.com"},{"@type":"BreadcrumbList","@id":"https:\/\/www.rekubik.de\/magazin\/komposter-selber-bauen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rekubik.de\/magazin\/"},{"@type":"ListItem","position":2,"name":"Komposter selber bauen"}]},{"@type":"WebSite","@id":"https:\/\/www.rekubik.de\/magazin\/#website","url":"https:\/\/www.rekubik.de\/magazin\/","name":"REKUBIK\u00ae Magazin","description":"","publisher":{"@id":"https:\/\/www.rekubik.de\/magazin\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rekubik.de\/magazin\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.rekubik.de\/magazin\/#organization","name":"Rekubik","url":"https:\/\/www.rekubik.de\/magazin\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.rekubik.de\/magazin\/#\/schema\/logo\/image\/","url":"https:\/\/www.rekubik.de\/magazin\/wp-content\/uploads\/2017\/12\/rekubik-LOGO-Shopware.png","contentUrl":"https:\/\/www.rekubik.de\/magazin\/wp-content\/uploads\/2017\/12\/rekubik-LOGO-Shopware.png","width":200,"height":50,"caption":"Rekubik"},"image":{"@id":"https:\/\/www.rekubik.de\/magazin\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.rekubik.de\/magazin\/#\/schema\/person\/d5faea021aac94edeeb8e47cf06771c7","name":"admin","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.rekubik.de\/magazin\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a794a4fe8a9b9c52241597eb381dfa2e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a794a4fe8a9b9c52241597eb381dfa2e?s=96&d=mm&r=g","caption":"admin"}}]}},"_links":{"self":[{"href":"https:\/\/www.rekubik.de\/magazin\/wp-json\/wp\/v2\/posts\/2562"}],"collection":[{"href":"https:\/\/www.rekubik.de\/magazin\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rekubik.de\/magazin\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rekubik.de\/magazin\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rekubik.de\/magazin\/wp-json\/wp\/v2\/comments?post=2562"}],"version-history":[{"count":38,"href":"https:\/\/www.rekubik.de\/magazin\/wp-json\/wp\/v2\/posts\/2562\/revisions"}],"predecessor-version":[{"id":20758,"href":"https:\/\/www.rekubik.de\/magazin\/wp-json\/wp\/v2\/posts\/2562\/revisions\/20758"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rekubik.de\/magazin\/wp-json\/wp\/v2\/media\/2578"}],"wp:attachment":[{"href":"https:\/\/www.rekubik.de\/magazin\/wp-json\/wp\/v2\/media?parent=2562"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rekubik.de\/magazin\/wp-json\/wp\/v2\/categories?post=2562"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rekubik.de\/magazin\/wp-json\/wp\/v2\/tags?post=2562"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}