{"id":3940,"date":"2019-03-25T08:57:40","date_gmt":"2019-03-25T07:57:40","guid":{"rendered":"https:\/\/www.rekubik.de\/magazin\/?p=3940"},"modified":"2024-10-01T15:43:41","modified_gmt":"2024-10-01T13:43:41","slug":"un-zulassung-fuer-ibc-container","status":"publish","type":"post","link":"https:\/\/www.rekubik.de\/magazin\/un-zulassung-fuer-ibc-container\/","title":{"rendered":"UN-Zulassung f\u00fcr IBC Container"},"content":{"rendered":"<h2>\u00ab Was sagt die Kennzeichnung \u00fcber Verpackungsmaterial aus? \u00bb<\/h2>\n<p style=\"text-align: justify;\"><strong>Wer mit dem Transport von G\u00fctern zu tun hat, begegnet mit sch\u00f6ner Regelm\u00e4\u00dfigkeit dem Ausdruck UN-Zulassung. Gemeint ist damit, dass insbesondere Gefahrg\u00fcter nur in Beh\u00e4ltern transportiert werden d\u00fcrfen, die auch daf\u00fcr zugelassen sind. Die Kriterien daf\u00fcr werden von den Vereinten Nationen (UN) festgelegt. Was es sonst noch dar\u00fcber zu wissen gilt und vor allem wie es mit der UN-Zulassung f\u00fcr <\/strong><a href=\"https:\/\/www.rekubik.de\/ibc-container\/\"><strong>IBC Container<\/strong><\/a><strong> aussieht, k\u00f6nnen Sie hier nachlesen.<\/strong><\/p>\n<h2>Gef\u00e4hrliche G\u00fcter<\/h2>\n<p style=\"text-align: justify;\">Es gibt eine ganze Reihe von G\u00fctern, die zumindest theoretisch f\u00fcr Menschen und die Umwelt gef\u00e4hrlich sind. Zu denken w\u00e4re hier etwa an bestimmte S\u00e4uren und Laugen oder giftige Chemikalien. Meist werden diese G\u00fcter f\u00fcr die Herstellung bestimmter Produkte zwingend ben\u00f6tigt. Das bedeutet dann auch, dass sie transportiert werden m\u00fcssen. Und genau hier beginnen die Probleme. Der Transport im \u00f6ffentlichen Raum stellt n\u00e4mlich das gr\u00f6\u00dfte Risiko dar, dass so ein Stoff freigesetzt wird und dann erhebliche Sch\u00e4den anrichtet oder sogar Menschenleben gef\u00e4hrdet. Um dieses Risiko m\u00f6glichst gering zu halten, gibt es nationale wie internationale Vorschriften f\u00fcr einen Gefahrenguttransport. Darin ist dann unter anderem geregelt, in welcher Art von <a href=\"https:\/\/www.rekubik.de\/industrie-lagertechnik\/\">Industrieverpackung<\/a> welches gef\u00e4hrliche Gefahrengut transportiert werden darf. Anders ausgedr\u00fcckt: Die jeweiligen Transportbeh\u00e4ltnisse ben\u00f6tigen eine Zulassung, mit der best\u00e4tigt wird, dass sie auch tats\u00e4chlich f\u00fcr ein bestimmtes Gut geeignet sind. Wichtigstes Kriterium dabei ist die Dichtheit des Beh\u00e4lters. Dar\u00fcber hinaus muss unbedingt auch gew\u00e4hrleistet sein, dass das Material, aus dem er gefertigt wurde, nicht mit dem Inhalt reagiert. Die \u00fcbergreifenden Regeln daf\u00fcr gelten weltweit. Sie wurden von den Vereinten Nationen festgelegt.<\/p>\n<p>\u00a0 <a href=\"https:\/\/www.rekubik.de\/industrie-lagertechnik\/thermoschutz\/thermohaube-geschlossen-fuer-industriepalette-1200-x-1000-mm\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-3943 \" title=\"Thermohaube geschlossen f\u00fcr Industriepalette 1200 x 1000 mm\" src=\"https:\/\/www.rekubik.de\/magazin\/wp-content\/uploads\/2019\/03\/Thermohaube-geschlossen-f\u00fcr-Industriepalette-1200-x-1000-mm.jpg\" alt=\"Thermohaube geschlossen f\u00fcr Industriepalette 1200 x 1000 mm\" width=\"365\" height=\"366\" srcset=\"https:\/\/www.rekubik.de\/magazin\/wp-content\/uploads\/2019\/03\/Thermohaube-geschlossen-f\u00fcr-Industriepalette-1200-x-1000-mm.jpg 400w, https:\/\/www.rekubik.de\/magazin\/wp-content\/uploads\/2019\/03\/Thermohaube-geschlossen-f\u00fcr-Industriepalette-1200-x-1000-mm-300x300.jpg 300w, https:\/\/www.rekubik.de\/magazin\/wp-content\/uploads\/2019\/03\/Thermohaube-geschlossen-f\u00fcr-Industriepalette-1200-x-1000-mm-150x150.jpg 150w\" sizes=\"(max-width: 365px) 100vw, 365px\" \/><\/a>\u00a0 \u00a0\u00a0<a href=\"https:\/\/www.rekubik.de\/kanister-zubehoer\/zubehoer\/220l-fass-thermohaube-rundhaube\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-3944\" title=\"220l Fass Thermohaube Rundhaube\" src=\"https:\/\/www.rekubik.de\/magazin\/wp-content\/uploads\/2019\/03\/220l-Fass-Thermohaube-Rundhaube.jpg\" alt=\"220l Fass Thermohaube Rundhaube\" width=\"365\" height=\"366\" srcset=\"https:\/\/www.rekubik.de\/magazin\/wp-content\/uploads\/2019\/03\/220l-Fass-Thermohaube-Rundhaube.jpg 400w, https:\/\/www.rekubik.de\/magazin\/wp-content\/uploads\/2019\/03\/220l-Fass-Thermohaube-Rundhaube-300x300.jpg 300w, https:\/\/www.rekubik.de\/magazin\/wp-content\/uploads\/2019\/03\/220l-Fass-Thermohaube-Rundhaube-150x150.jpg 150w\" sizes=\"(max-width: 365px) 100vw, 365px\" \/><\/a><\/p>\n<h2>Was genau ist eigentlich die UN-Zulassung?<\/h2>\n<p style=\"text-align: justify;\">Der weltweite Handel und die stetig fortschreitende Globalisierung f\u00fchren dazu, dass G\u00fcter heute nicht mehr nur \u00fcber L\u00e4ndergrenzen hinweg transportiert werden, sondern auch von Kontinent zu Kontinent wandern. Ein Gefahrengut, das in Deutschland gef\u00e4hrlich ist, ist aber auch in jedem anderen Land der Erde gef\u00e4hrlich. Ganz zu schweigen davon, dass auch in der Luft oder auf den Weltmeeren erhebliche Probleme damit auftreten k\u00f6nnen. Vor diesem Hintergrund begann bereits in den 1990er Jahren eine intensive Diskussion \u00fcber gewisse Standards beim Gefahrenguttransport bei den Vereinten Nationen. Ziel war es, ein Regelwerk zu entwickeln, dass weltweit G\u00fcltigkeit hat und den Mitgliedsstaaten eine Orientierung im Umgang mit der Thematik bietet. Diese Diskussionen m\u00fcndeten im Jahr 2000 schlie\u00dflich in den &#8222;UN Recommendations on the Transport of Dangerous Goods&#8220;. In ihnen wurde der Umgang mit gef\u00e4hrlichen G\u00fctern beim Transport festgelegt. Ein zentrales Element dabei ist eine umfangreiche Liste mit Stoffnummern. In ihr wird jedem potenziell gef\u00e4hrlichen Stoff eine vierstellige Ziffernkombination zugeordnet. Jeder Stoff l\u00e4sst sich anhand dieser Liste weltweit eindeutig identifizieren. Ist im Zusammenhang mit einer Transport- bzw. Industrieverpackung von der UN-Zulassung die Rede, dann geht es immer darum, dass das Beh\u00e4ltnis f\u00fcr bestimmter G\u00fcter auf dieser Liste geeignet sein muss. Die Liste wird \u00fcbrigens regelm\u00e4\u00dfig von einer Expertenkommission der Vereinten Nationen aktualisiert.<\/p>\n<figure id=\"attachment_3960\" aria-describedby=\"caption-attachment-3960\" style=\"width: 850px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-3960 size-full\" title=\"IBCs im Lager\" src=\"https:\/\/www.rekubik.de\/magazin\/wp-content\/uploads\/2019\/03\/Lager.jpg\" alt=\"IBCs im Lager\" width=\"850\" height=\"494\" srcset=\"https:\/\/www.rekubik.de\/magazin\/wp-content\/uploads\/2019\/03\/Lager.jpg 850w, https:\/\/www.rekubik.de\/magazin\/wp-content\/uploads\/2019\/03\/Lager-300x174.jpg 300w, https:\/\/www.rekubik.de\/magazin\/wp-content\/uploads\/2019\/03\/Lager-768x446.jpg 768w\" sizes=\"(max-width: 850px) 100vw, 850px\" \/><figcaption id=\"caption-attachment-3960\" class=\"wp-caption-text\">\u00a9 Amarinj \u2013 stock.adobe.com<\/figcaption><\/figure>\n<h2>Stoffnummern \u2013 weltweit ein Gefahrengut eindeutig identifizieren<\/h2>\n<p style=\"text-align: justify;\">Wie bereits erw\u00e4hnt, bestehen die Stoffnummern aus einer vierstelligen Ziffernkombination. Mit dieser Kombination l\u00e4sst sich ein gef\u00e4hrliches Gut weltweit und \u00fcber Sprachgrenzen hinweg eindeutig identifizieren und einer bestimmten Gefahrgutklasse zuordnen. Die Stoffnummer &#8222;0209&#8220; steht beispielsweise f\u00fcr Trinitrotoluol in einem trockenen oder angefeuchteten Zustand mit weniger als 30 Masse-Prozent Wasser.<\/p>\n<p><a href=\"https:\/\/www.rekubik.de\/ibc-container\/neue-ibc\/1000l-ibc-container-un-zulassung-auf-pe-palette-neu\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-3953\" style=\"text-align: justify;\" title=\"1000l IBC Container UN-Zulassung auf PE-Palette NEU\" src=\"https:\/\/www.rekubik.de\/magazin\/wp-content\/uploads\/2019\/03\/1000l-IBC-Container-UN-Zulassung-auf-PE-Palette-NEU.jpg\" alt=\"1000l IBC Container UN-Zulassung auf PE-Palette NEU\" width=\"390\" height=\"450\" srcset=\"https:\/\/www.rekubik.de\/magazin\/wp-content\/uploads\/2019\/03\/1000l-IBC-Container-UN-Zulassung-auf-PE-Palette-NEU.jpg 400w, https:\/\/www.rekubik.de\/magazin\/wp-content\/uploads\/2019\/03\/1000l-IBC-Container-UN-Zulassung-auf-PE-Palette-NEU-260x300.jpg 260w\" sizes=\"(max-width: 390px) 100vw, 390px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Weil Trinitrotoluol, das hierzulande besser als TNT bekannt ist, ein hochexplosiver Sprengstoff ist, wird er in die Gefahrgutklasse 1 eingeordnet, zu der ganz allgemein Explosivstoffe und G\u00fcter, die Explosivstoffe enthalten, geh\u00f6ren.Mit dieser Kombination kann nun sehr leicht festgestellt werden, ob ein bestimmtes Beh\u00e4ltnis f\u00fcr den Transport des TNTs zugelassen ist \u2013 und zwar \u00fcberall auf der Welt und ganz unabh\u00e4ngig von der jeweiligen Landessprache. Damit dies auch wirklich funktioniert, muss der Hersteller eines Beh\u00e4lters nach bestimmten Kriterien verpflichtend angeben, f\u00fcr welche Stoffe sein Produkt die entsprechende Zulassung hat. Nur wenn diese vorliegt, darf etwa das TNT auch darin transportiert werden. Die Stoffnummern und die Gefahrgutklasse spielen im \u00dcbrigen auch im Katastrophenfall eine Rolle. Feuerwehren und Rettungshelfer weltweit k\u00f6nnen sich durch sie n\u00e4mlich sehr schnell dar\u00fcber informieren, mit welchem Stoff sie es \u00fcberhaupt zu tun haben und wie damit umzugehen ist.<\/p>\n<h2>UN-Zulassung f\u00fcr IBC \u2013 Besonderheiten und Vorteile der Container<\/h2>\n<p style=\"text-align: justify;\">IBCs haben sich l\u00e4ngst zu einem sehr beliebten und weit verbreiteten Lager- und Transportbeh\u00e4lter entwickelt. Der Grund daf\u00fcr ist nat\u00fcrlich die hohe Funktionalit\u00e4t, die ein IBC mit sich bringt. Er kann auch f\u00fcr gef\u00e4hrliche G\u00fcter und einen Gefahrenguttransport verwendet werden. Allerdings gilt dies nicht pauschal. Der betreffende IBC muss vielmehr f\u00fcr das jeweilige Gut explizit zugelassen sein. Er muss sich au\u00dferdem in einem einwandfreien Zustand befinden. Und er darf ein bestimmtes Alter nicht \u00fcberschreiten. Die UN-Zulassung f\u00fcr IBCs wird folglich durch weitere, meist nationale Vorschriften flankiert. In denen ist dann etwa geregelt, dass der Container regelm\u00e4\u00dfig auf seine Tauglichkeit hin \u00fcberpr\u00fcft werden muss. Werden M\u00e4ngel festgestellt, m\u00fcssen diese umgehend behoben werden. Ist dies nicht m\u00f6glich, verliert er seine Genehmigung f\u00fcr das jeweilige Gefahrengut und darf nicht mehr zum Einsatz kommen. IBCs sind zweifellos f\u00fcr den Transport gef\u00e4hrlicher G\u00fcter ideal. Ihre besondere Konstruktion erm\u00f6glicht vor allem ein sehr sicheres Be- und Entladen. Der Umgang mit diesen Beh\u00e4ltern ist denkbar einfach. Verbaut in der Gitterbox, die standardm\u00e4\u00dfig die Tankblase umgibt, ist meist eine freie Fl\u00e4che, die mit dem sogenannten Gefahrzettel beklebt werden kann. Auf diesem Zettel befinden sich Symbole, die schon auf den ersten Blick Auskunft \u00fcber den Inhalt des Containers geben. So sind eine leichtere Identifikation und damit auch mehr Sicherheit m\u00f6glich.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00ab Was sagt die Kennzeichnung \u00fcber Verpackungsmaterial aus? \u00bb Wer mit dem Transport von G\u00fctern zu tun hat, begegnet mit sch\u00f6ner Regelm\u00e4\u00dfigkeit dem Ausdruck UN-Zulassung. Gemeint ist damit, dass insbesondere Gefahrg\u00fcter nur in Beh\u00e4ltern transportiert werden d\u00fcrfen, die auch daf\u00fcr zugelassen sind. Die Kriterien daf\u00fcr werden von den Vereinten Nationen (UN) festgelegt. Was es sonst &hellip;<\/p>\n","protected":false},"author":1,"featured_media":3958,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[98,99,7,205,75,466,467],"class_list":["post-3940","post","type-post","status-publish","format-standard","has-post-thumbnail","","category-ibc-unternehmen","tag-gefahrengut","tag-gefahrenguttransport","tag-ibc","tag-ibc-container","tag-un-zulassung","tag-un-zulassung-fuer-ibc-container","tag-zulassung"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>UN-Zulassung f\u00fcr IBC Container - REKUBIK\u00ae Magazin<\/title>\n<meta name=\"description\" content=\"Das Rekubik Magazin erkl\u00e4rt, was die UN-Zulassung bedeutet \u2714 und welche Kriterien daf\u00fcr im Falle von IBC Containern n\u00f6tig sind \u2714\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rekubik.de\/magazin\/un-zulassung-fuer-ibc-container\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"UN-Zulassung f\u00fcr IBC Container - REKUBIK\u00ae Magazin\" \/>\n<meta property=\"og:description\" content=\"Das Rekubik Magazin erkl\u00e4rt, was die UN-Zulassung bedeutet \u2714 und welche Kriterien daf\u00fcr im Falle von IBC Containern n\u00f6tig sind \u2714\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rekubik.de\/magazin\/un-zulassung-fuer-ibc-container\/\" \/>\n<meta property=\"og:site_name\" content=\"REKUBIK\u00ae Magazin\" \/>\n<meta property=\"article:published_time\" content=\"2019-03-25T07:57:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-01T13:43:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rekubik.de\/magazin\/wp-content\/uploads\/2019\/03\/Gefahrgut.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"850\" \/>\n\t<meta property=\"og:image:height\" content=\"497\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschrieben von\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.rekubik.de\/magazin\/un-zulassung-fuer-ibc-container\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.rekubik.de\/magazin\/un-zulassung-fuer-ibc-container\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\/\/www.rekubik.de\/magazin\/#\/schema\/person\/d5faea021aac94edeeb8e47cf06771c7\"},\"headline\":\"UN-Zulassung f\u00fcr IBC Container\",\"datePublished\":\"2019-03-25T07:57:40+00:00\",\"dateModified\":\"2024-10-01T13:43:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.rekubik.de\/magazin\/un-zulassung-fuer-ibc-container\/\"},\"wordCount\":989,\"publisher\":{\"@id\":\"https:\/\/www.rekubik.de\/magazin\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.rekubik.de\/magazin\/un-zulassung-fuer-ibc-container\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.rekubik.de\/magazin\/wp-content\/uploads\/2019\/03\/Gefahrgut.jpg\",\"keywords\":[\"Gefahrengut\",\"Gefahrenguttransport\",\"IBC\",\"IBC Container\",\"UN-Zulassung\",\"UN-Zulassung f\u00fcr IBC Container\",\"Zulassung\"],\"articleSection\":[\"IBC IN UNTERNEHMEN\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.rekubik.de\/magazin\/un-zulassung-fuer-ibc-container\/\",\"url\":\"https:\/\/www.rekubik.de\/magazin\/un-zulassung-fuer-ibc-container\/\",\"name\":\"UN-Zulassung f\u00fcr IBC Container - REKUBIK\u00ae Magazin\",\"isPartOf\":{\"@id\":\"https:\/\/www.rekubik.de\/magazin\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.rekubik.de\/magazin\/un-zulassung-fuer-ibc-container\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.rekubik.de\/magazin\/un-zulassung-fuer-ibc-container\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.rekubik.de\/magazin\/wp-content\/uploads\/2019\/03\/Gefahrgut.jpg\",\"datePublished\":\"2019-03-25T07:57:40+00:00\",\"dateModified\":\"2024-10-01T13:43:41+00:00\",\"description\":\"Das Rekubik Magazin erkl\u00e4rt, was die UN-Zulassung bedeutet \u2714 und welche Kriterien daf\u00fcr im Falle von IBC Containern n\u00f6tig sind \u2714\",\"breadcrumb\":{\"@id\":\"https:\/\/www.rekubik.de\/magazin\/un-zulassung-fuer-ibc-container\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.rekubik.de\/magazin\/un-zulassung-fuer-ibc-container\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.rekubik.de\/magazin\/un-zulassung-fuer-ibc-container\/#primaryimage\",\"url\":\"https:\/\/www.rekubik.de\/magazin\/wp-content\/uploads\/2019\/03\/Gefahrgut.jpg\",\"contentUrl\":\"https:\/\/www.rekubik.de\/magazin\/wp-content\/uploads\/2019\/03\/Gefahrgut.jpg\",\"width\":850,\"height\":497,\"caption\":\"\u00a9 Bj\u00f6rn Wylezich \u2013 stock.adobe.com\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.rekubik.de\/magazin\/un-zulassung-fuer-ibc-container\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.rekubik.de\/magazin\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"UN-Zulassung f\u00fcr IBC Container\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.rekubik.de\/magazin\/#website\",\"url\":\"https:\/\/www.rekubik.de\/magazin\/\",\"name\":\"REKUBIK\u00ae Magazin\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.rekubik.de\/magazin\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.rekubik.de\/magazin\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.rekubik.de\/magazin\/#organization\",\"name\":\"Rekubik\",\"url\":\"https:\/\/www.rekubik.de\/magazin\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.rekubik.de\/magazin\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.rekubik.de\/magazin\/wp-content\/uploads\/2017\/12\/rekubik-LOGO-Shopware.png\",\"contentUrl\":\"https:\/\/www.rekubik.de\/magazin\/wp-content\/uploads\/2017\/12\/rekubik-LOGO-Shopware.png\",\"width\":200,\"height\":50,\"caption\":\"Rekubik\"},\"image\":{\"@id\":\"https:\/\/www.rekubik.de\/magazin\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.rekubik.de\/magazin\/#\/schema\/person\/d5faea021aac94edeeb8e47cf06771c7\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.rekubik.de\/magazin\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a794a4fe8a9b9c52241597eb381dfa2e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a794a4fe8a9b9c52241597eb381dfa2e?s=96&d=mm&r=g\",\"caption\":\"admin\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"UN-Zulassung f\u00fcr IBC Container - REKUBIK\u00ae Magazin","description":"Das Rekubik Magazin erkl\u00e4rt, was die UN-Zulassung bedeutet \u2714 und welche Kriterien daf\u00fcr im Falle von IBC Containern n\u00f6tig sind \u2714","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rekubik.de\/magazin\/un-zulassung-fuer-ibc-container\/","og_locale":"de_DE","og_type":"article","og_title":"UN-Zulassung f\u00fcr IBC Container - REKUBIK\u00ae Magazin","og_description":"Das Rekubik Magazin erkl\u00e4rt, was die UN-Zulassung bedeutet \u2714 und welche Kriterien daf\u00fcr im Falle von IBC Containern n\u00f6tig sind \u2714","og_url":"https:\/\/www.rekubik.de\/magazin\/un-zulassung-fuer-ibc-container\/","og_site_name":"REKUBIK\u00ae Magazin","article_published_time":"2019-03-25T07:57:40+00:00","article_modified_time":"2024-10-01T13:43:41+00:00","og_image":[{"width":850,"height":497,"url":"https:\/\/www.rekubik.de\/magazin\/wp-content\/uploads\/2019\/03\/Gefahrgut.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Geschrieben von":"admin","Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rekubik.de\/magazin\/un-zulassung-fuer-ibc-container\/#article","isPartOf":{"@id":"https:\/\/www.rekubik.de\/magazin\/un-zulassung-fuer-ibc-container\/"},"author":{"name":"admin","@id":"https:\/\/www.rekubik.de\/magazin\/#\/schema\/person\/d5faea021aac94edeeb8e47cf06771c7"},"headline":"UN-Zulassung f\u00fcr IBC Container","datePublished":"2019-03-25T07:57:40+00:00","dateModified":"2024-10-01T13:43:41+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rekubik.de\/magazin\/un-zulassung-fuer-ibc-container\/"},"wordCount":989,"publisher":{"@id":"https:\/\/www.rekubik.de\/magazin\/#organization"},"image":{"@id":"https:\/\/www.rekubik.de\/magazin\/un-zulassung-fuer-ibc-container\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rekubik.de\/magazin\/wp-content\/uploads\/2019\/03\/Gefahrgut.jpg","keywords":["Gefahrengut","Gefahrenguttransport","IBC","IBC Container","UN-Zulassung","UN-Zulassung f\u00fcr IBC Container","Zulassung"],"articleSection":["IBC IN UNTERNEHMEN"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.rekubik.de\/magazin\/un-zulassung-fuer-ibc-container\/","url":"https:\/\/www.rekubik.de\/magazin\/un-zulassung-fuer-ibc-container\/","name":"UN-Zulassung f\u00fcr IBC Container - REKUBIK\u00ae Magazin","isPartOf":{"@id":"https:\/\/www.rekubik.de\/magazin\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rekubik.de\/magazin\/un-zulassung-fuer-ibc-container\/#primaryimage"},"image":{"@id":"https:\/\/www.rekubik.de\/magazin\/un-zulassung-fuer-ibc-container\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rekubik.de\/magazin\/wp-content\/uploads\/2019\/03\/Gefahrgut.jpg","datePublished":"2019-03-25T07:57:40+00:00","dateModified":"2024-10-01T13:43:41+00:00","description":"Das Rekubik Magazin erkl\u00e4rt, was die UN-Zulassung bedeutet \u2714 und welche Kriterien daf\u00fcr im Falle von IBC Containern n\u00f6tig sind \u2714","breadcrumb":{"@id":"https:\/\/www.rekubik.de\/magazin\/un-zulassung-fuer-ibc-container\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rekubik.de\/magazin\/un-zulassung-fuer-ibc-container\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.rekubik.de\/magazin\/un-zulassung-fuer-ibc-container\/#primaryimage","url":"https:\/\/www.rekubik.de\/magazin\/wp-content\/uploads\/2019\/03\/Gefahrgut.jpg","contentUrl":"https:\/\/www.rekubik.de\/magazin\/wp-content\/uploads\/2019\/03\/Gefahrgut.jpg","width":850,"height":497,"caption":"\u00a9 Bj\u00f6rn Wylezich \u2013 stock.adobe.com"},{"@type":"BreadcrumbList","@id":"https:\/\/www.rekubik.de\/magazin\/un-zulassung-fuer-ibc-container\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rekubik.de\/magazin\/"},{"@type":"ListItem","position":2,"name":"UN-Zulassung f\u00fcr IBC Container"}]},{"@type":"WebSite","@id":"https:\/\/www.rekubik.de\/magazin\/#website","url":"https:\/\/www.rekubik.de\/magazin\/","name":"REKUBIK\u00ae Magazin","description":"","publisher":{"@id":"https:\/\/www.rekubik.de\/magazin\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rekubik.de\/magazin\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.rekubik.de\/magazin\/#organization","name":"Rekubik","url":"https:\/\/www.rekubik.de\/magazin\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.rekubik.de\/magazin\/#\/schema\/logo\/image\/","url":"https:\/\/www.rekubik.de\/magazin\/wp-content\/uploads\/2017\/12\/rekubik-LOGO-Shopware.png","contentUrl":"https:\/\/www.rekubik.de\/magazin\/wp-content\/uploads\/2017\/12\/rekubik-LOGO-Shopware.png","width":200,"height":50,"caption":"Rekubik"},"image":{"@id":"https:\/\/www.rekubik.de\/magazin\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.rekubik.de\/magazin\/#\/schema\/person\/d5faea021aac94edeeb8e47cf06771c7","name":"admin","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.rekubik.de\/magazin\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a794a4fe8a9b9c52241597eb381dfa2e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a794a4fe8a9b9c52241597eb381dfa2e?s=96&d=mm&r=g","caption":"admin"}}]}},"_links":{"self":[{"href":"https:\/\/www.rekubik.de\/magazin\/wp-json\/wp\/v2\/posts\/3940"}],"collection":[{"href":"https:\/\/www.rekubik.de\/magazin\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rekubik.de\/magazin\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rekubik.de\/magazin\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rekubik.de\/magazin\/wp-json\/wp\/v2\/comments?post=3940"}],"version-history":[{"count":20,"href":"https:\/\/www.rekubik.de\/magazin\/wp-json\/wp\/v2\/posts\/3940\/revisions"}],"predecessor-version":[{"id":22589,"href":"https:\/\/www.rekubik.de\/magazin\/wp-json\/wp\/v2\/posts\/3940\/revisions\/22589"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rekubik.de\/magazin\/wp-json\/wp\/v2\/media\/3958"}],"wp:attachment":[{"href":"https:\/\/www.rekubik.de\/magazin\/wp-json\/wp\/v2\/media?parent=3940"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rekubik.de\/magazin\/wp-json\/wp\/v2\/categories?post=3940"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rekubik.de\/magazin\/wp-json\/wp\/v2\/tags?post=3940"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}